{"id":779,"date":"2023-11-09T01:31:55","date_gmt":"2023-11-09T01:31:55","guid":{"rendered":"https:\/\/gymguyz.wpenginepowered.com\/des-moines\/?page_id=779"},"modified":"2024-08-08T05:39:32","modified_gmt":"2024-08-08T05:39:32","slug":"strength-training","status":"publish","type":"page","link":"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/strength-training\/","title":{"rendered":"Strength Training"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"779\" class=\"elementor elementor-779\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4635c8b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4635c8b7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-18adc0ae\" data-id=\"18adc0ae\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2dca9594 elementor-widget elementor-widget-heading\" data-id=\"2dca9594\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">STRENGTH TRAINING\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c815056 elementor-widget elementor-widget-heading\" data-id=\"1c815056\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">OUR PERSONAL TRAINERS CREATE A CUSTOMIZED FITNESS PROGRAM FOR YOU\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27e142b3 elementor-widget elementor-widget-text-editor\" data-id=\"27e142b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The GYMGUYZ strength training programs are geared toward helping you improve your fitness levels and overall health. One of our experienced, certified trainers will coach and guide you through a routine created for you to help increase your strength and energy so you can look and feel your best.<\/p><p>Strength training uses resistance to introduce muscular contraction and help build anaerobic endurance, increase the size of your skeletal muscles, and build strength. Combining different exercises, number of sets, repetitions, and changing up tempos builds muscle strength and allows you to achieve the desired results. Strength training is effective in weight loss programs and in the treatment of chronic conditions such as back pain and arthritis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6623f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b6623f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c33c15 elementor-widget elementor-widget-text-editor\" data-id=\"4c33c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article id=\"ContentZone\" class=\"two-thirds\"><div id=\"MainContent\" class=\"content\" tabindex=\"0\" data-content=\"true\"><p class=\"text-highlight v1\" align=\"center\"><strong>Schedule your first session today by calling\u00a0<a id=\"MainContent_1\" href=\"tel:(208) 943-2712\">(208) 943-2712<\/a>. The first one is on us!<\/strong><\/p><\/div><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ce3c82 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"8ce3c82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3a9c1 elementor-widget elementor-widget-heading\" data-id=\"eb3a9c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TRAINERS &amp; PROGRAMS THAT COME TO IN-PERSON OR VIRTUALLY\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9fd9ca elementor-widget elementor-widget-text-editor\" data-id=\"c9fd9ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>GYMGUYZ personal trainers create strength training routines specific for each client using GYMGUYZ equipment and frequently developing strength through the use of the body as a tool.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ed418 elementor-widget elementor-widget-heading\" data-id=\"b0ed418\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">THE BENEFITS OF STRENGTH TRAINING\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4051418f elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4051418f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Increased Muscle Strength<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Boosted Metabolism<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Improved Bone Density<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enhanced Joint Health<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cardiovascular Health<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Weight Management<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f77931f elementor-widget elementor-widget-text-editor\" data-id=\"f77931f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Take the first step towards a healthier, stronger you by joining our strength training program. Our personal trainers at GYMGUYZ Greater Boise are here to guide you on your fitness journey and help you achieve your goals. Whether you&#8217;re a beginner or an experienced athlete, our personalized approach ensures that you&#8217;ll get the most out of every session.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1edd2b9 elementor-widget elementor-widget-text-editor\" data-id=\"1edd2b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our strength training programs are designed to make you stronger, more energetic, and confident in your own skin. Our experienced personal trainers work closely with you to create a customized routine that targets your individual goals. Whether you&#8217;re aiming to build muscle, lose weight, or increase your overall strength, we&#8217;ve got you covered.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccc5648 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ccc5648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5867fd3 elementor-widget elementor-widget-text-editor\" data-id=\"5867fd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<article id=\"ContentZone\" class=\"two-thirds\">\n<div id=\"MainContent\" class=\"content\" tabindex=\"0\" data-content=\"true\">\n<p class=\"text-highlight v1\">Experience the power of strength training! Call&nbsp;(208) 943-2712&nbsp;or&nbsp;<a href=\"\/greater-boise-id\/contact\/\">contact us online<\/a>&nbsp;to get in touch with our strength trainers today!<\/p><\/div><\/article>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-357d7b9 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"357d7b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-32fa0a60\" data-id=\"32fa0a60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-e694566 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e694566\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4a9a0de2\" data-id=\"4a9a0de2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51fbfd32 elementor-widget elementor-widget-image\" data-id=\"51fbfd32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"499\" height=\"325\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Training-Services-from-GYMGUYZ-East-Valley-1.webp\" class=\"attachment-full size-full wp-image-1056\" alt=\"Training-Services-from-GYMGUYZ\" srcset=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Training-Services-from-GYMGUYZ-East-Valley-1.webp 499w, https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Training-Services-from-GYMGUYZ-East-Valley-1-300x195.webp 300w\" sizes=\"(max-width: 499px) 100vw, 499px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9c72e elementor-widget elementor-widget-global elementor-global-1154 elementor-widget-heading\" data-id=\"5f9c72e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"\/greater-boise-id\/training-services\/\">Training Services<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c6b231 elementor-nav-menu--dropdown-none custom-sidebar-menu elementor-widget elementor-widget-nav-menu\" data-id=\"29c6b231\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-29c6b231\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-407\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/cardio-fitness\/\" class=\"elementor-item menu-link\">Cardio Fitness<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1151\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/stretch\/\" class=\"elementor-item menu-link\">Stretch<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-845\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/virtual-personal-training\/\" class=\"elementor-item menu-link\">Virtual Personal Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-550\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/group-training\/\" class=\"elementor-item menu-link\">Group Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-838\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/nutrition-counseling\/\" class=\"elementor-item menu-link\">Nutrition Counseling<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-839\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/pre-natal-exercise\/\" class=\"elementor-item menu-link\">Pre\/Post Natal Exercise<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-840\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/senior-fitness-training\/\" class=\"elementor-item menu-link\">Senior Fitness Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-841\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/speciality-services\/\" class=\"elementor-item menu-link\">Speciality Services<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-842\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/sports-conditioning\/\" class=\"elementor-item menu-link\">Sports Conditioning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-843\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/strength-training\/\" class=\"elementor-item menu-link\">Strength Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-846\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/weight-loss-toning\/\" class=\"elementor-item menu-link\">Weight Loss &amp; Toning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-847\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/weight-resistance-training\/\" class=\"elementor-item menu-link\">Weight Resistance Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-848\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/youth-teen-fitness\/\" class=\"elementor-item menu-link\">Youth Teen Fitness<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-29c6b231\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-407\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/cardio-fitness\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Cardio Fitness<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1151\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/stretch\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Stretch<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-845\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/virtual-personal-training\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Virtual Personal Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-550\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/group-training\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Group Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-838\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/nutrition-counseling\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Nutrition Counseling<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-839\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/pre-natal-exercise\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Pre\/Post Natal Exercise<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-840\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/senior-fitness-training\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Senior Fitness Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-841\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/speciality-services\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Speciality Services<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-842\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/sports-conditioning\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Sports Conditioning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-843\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/strength-training\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Strength Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-846\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/weight-loss-toning\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Weight Loss &amp; Toning<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-847\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/weight-resistance-training\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Weight Resistance Training<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-848\"><a href=\"https:\/\/www.gymguyz.com\/greater-boise-id\/training-services\/youth-teen-fitness\/\" class=\"elementor-item menu-link\" tabindex=\"-1\">Youth Teen Fitness<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ab2f9f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ab2f9f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-93e9e01\" data-id=\"93e9e01\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ee36f33 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1ee36f33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">We Bring The<br> Workout To You<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f2df75 elementor-align-center elementor-widget elementor-widget-global elementor-global-1082 elementor-widget-button\" data-id=\"4f2df75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/greater-boise-id\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Started<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2bf357 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2bf357\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d2ceb33\" data-id=\"d2ceb33\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdfd5b1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"fdfd5b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">You have Questions, <br>we have answers<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85be1b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"85be1b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/why-choose-us\/faq\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FAQS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c5ab9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c5ab9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-75c8061\" data-id=\"75c8061\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db3976 elementor-widget elementor-widget-image\" data-id=\"4db3976\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"678\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/10\/Gym-Guyz-Free-Initial-Assessment.webp\" class=\"attachment-full size-full wp-image-72\" alt=\"Gym Guyz Free Initial Assessment\" srcset=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/10\/Gym-Guyz-Free-Initial-Assessment.webp 1000w, https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/10\/Gym-Guyz-Free-Initial-Assessment-300x203.webp 300w, https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/10\/Gym-Guyz-Free-Initial-Assessment-768x521.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ce4126 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0ce4126\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Customized Workout Plan Based On Your Goals<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c406e elementor-align-center elementor-widget elementor-widget-global elementor-global-1095 elementor-widget-button\" data-id=\"34c406e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/greater-boise-id\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Started<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5548f59d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5548f59d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60e8885b\" data-id=\"60e8885b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abe80c1 custom-counter elementor-widget elementor-widget-counter\" data-id=\"abe80c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">SEE THEIR TRANSFORMATIONS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\">OVER <\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100000\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><span>+<\/span> LIVES CHANGED<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40a1792 elementor-hidden-desktop elementor-hidden-tablet custom-logo-carousel elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"40a1792\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Heidi-Bound-Lost-50-lbs-with-gym-guyz.webp\" alt=\"Heidi Bound Lost 50 lbs with gym guyz\" \/><figcaption class=\"elementor-image-carousel-caption\">Heidi Bound Lost 50 Pounds<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Alan-Lost-90-Pounds-with-Gym-Guyz.webp\" alt=\"Alan Lost 90 Pounds with Gym Guyz\" \/><figcaption class=\"elementor-image-carousel-caption\">Alan Lost 90 Pounds<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/John-Pike-Lost-120-Pounds-with-Gym-Guyz.webp\" alt=\"John Pike Lost 120 Pounds with Gym Guyz\" \/><figcaption class=\"elementor-image-carousel-caption\">John Pike Lost 120 Pounds<\/figcaption><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-content\/uploads\/sites\/79\/2023\/11\/Evan-Lost-110-Pounds-with-Gym-Guyz.webp\" alt=\"Evan Lost 110 Pounds\" \/><figcaption class=\"elementor-image-carousel-caption\">Evan Lost 110 Pounds<\/figcaption><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e993d47 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e993d47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-185ee8b2\" data-id=\"185ee8b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11afeb76 elementor-flip-box--effect-push elementor-flip-box--direction-left elementor-widget elementor-widget-flip-box\" data-id=\"11afeb76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ceb941e elementor-widget elementor-widget-heading\" data-id=\"4ceb941e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Heidi Bound Lost 50 Pounds<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-58b54aca\" data-id=\"58b54aca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46c9a9ec elementor-flip-box--effect-push elementor-flip-box--direction-left elementor-widget elementor-widget-flip-box\" data-id=\"46c9a9ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff5a97b elementor-widget elementor-widget-heading\" data-id=\"ff5a97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">ALAN LOST 90 POUNDS\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-737f42cb\" data-id=\"737f42cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39a31ce4 elementor-flip-box--effect-push elementor-flip-box--direction-left elementor-widget elementor-widget-flip-box\" data-id=\"39a31ce4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-152d004a elementor-widget elementor-widget-heading\" data-id=\"152d004a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">JOHN PIKE LOST 120 POUNDS\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4772c242\" data-id=\"4772c242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2157ae4b elementor-flip-box--effect-push elementor-flip-box--direction-left elementor-widget elementor-widget-flip-box\" data-id=\"2157ae4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"flip-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-flip-box\" tabindex=\"0\">\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__front\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"elementor-flip-box__layer elementor-flip-box__back\">\n\t\t\t<div class=\"elementor-flip-box__layer__overlay\">\n\t\t\t\t<div class=\"elementor-flip-box__layer__inner\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48b7ce5b elementor-widget elementor-widget-heading\" data-id=\"48b7ce5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">EVAN LOST 110 POUNDS\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-71ca878a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71ca878a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-17fda33f\" data-id=\"17fda33f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c5bb0c elementor-align-center elementor-widget elementor-widget-global elementor-global-1092 elementor-widget-button\" data-id=\"5c5bb0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/before-afters\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">VIEW MORE TRANSFORMATIONS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-26d0437a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"26d0437a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d693ef3 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"5d693ef3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c5ff2d0 elementor-widget elementor-widget-spacer\" data-id=\"2c5ff2d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e03afa0\" data-id=\"1e03afa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bf36845 elementor-widget elementor-widget-heading\" data-id=\"6bf36845\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EXPERIENCE A\nDIFFERENT WAY\nTO WORK OUT<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9107a5 elementor-align-left elementor-tablet-align-center elementor-widget elementor-widget-global elementor-global-1089 elementor-widget-button\" data-id=\"e9107a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/greater-boise-id\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get Started<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>STRENGTH TRAINING OUR PERSONAL TRAINERS CREATE A CUSTOMIZED FITNESS PROGRAM FOR YOU The GYMGUYZ strength training programs are geared toward helping you improve your fitness levels and overall health. One of our experienced, certified trainers will coach and guide you through a routine created for you to help increase your strength and energy so you [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":168,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-779","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/pages\/779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/comments?post=779"}],"version-history":[{"count":0,"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/pages\/779\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/pages\/168"}],"wp:attachment":[{"href":"https:\/\/www.gymguyz.com\/greater-boise-id\/wp-json\/wp\/v2\/media?parent=779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}